{"id":3592,"date":"2017-06-30T20:45:05","date_gmt":"2017-06-30T18:45:05","guid":{"rendered":"https:\/\/www.berghaeuser.at\/baerenwald-country-lodge\/"},"modified":"2024-03-28T14:38:11","modified_gmt":"2024-03-28T13:38:11","slug":"country-lodge-baerenwald","status":"publish","type":"page","link":"https:\/\/www.berghaeuser.at\/en\/country-lodge-baerenwald\/","title":{"rendered":"Country lodge B\u00e4renwald"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page_default.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-3592","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.berghaeuser.at\/en\/wp-json\/wp\/v2\/pages\/3592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.berghaeuser.at\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.berghaeuser.at\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.berghaeuser.at\/en\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.berghaeuser.at\/en\/wp-json\/wp\/v2\/comments?post=3592"}],"version-history":[{"count":0,"href":"https:\/\/www.berghaeuser.at\/en\/wp-json\/wp\/v2\/pages\/3592\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.berghaeuser.at\/en\/wp-json\/wp\/v2\/media?parent=3592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}